{"id":6,"date":"2019-03-17T05:35:00","date_gmt":"2019-03-17T05:35:00","guid":{"rendered":"http:\/\/sublimesinterieurs.com\/?page_id=6"},"modified":"2024-05-13T14:02:32","modified_gmt":"2024-05-13T14:02:32","slug":"elementor-6","status":"publish","type":"page","link":"https:\/\/www.sublimesinterieurs.com\/","title":{"rendered":"Accueil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6\" class=\"elementor elementor-6\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a077502 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a077502\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90ca513\" data-id=\"90ca513\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dbfea3 elementor-widget elementor-widget-spacer\" data-id=\"2dbfea3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dae065a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dae065a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cr\u00e9er, ce n\u2019est pas reproduire ce qui existe d\u00e9j\u00e0, ce n\u2019est pas non plus faire une belle image mais faire \u00e0 son image...by C\u00e9line<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f74d176 elementor-widget elementor-widget-spacer\" data-id=\"f74d176\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e6de2ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6de2ff\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-95a2acb\" data-id=\"95a2acb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f422271 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"f422271\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"525\" height=\"787\" src=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-768x1151.jpg\" class=\"attachment-medium_large size-medium_large wp-image-833\" alt=\"Architecte d&apos;int\u00e9rieur\" srcset=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-768x1151.jpg 768w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-200x300.jpg 200w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-684x1024.jpg 684w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-1025x1536.jpg 1025w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-1367x2048.jpg 1367w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-350x524.jpg 350w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-scaled.jpg 1709w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aafe3a8\" data-id=\"aafe3a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22428ae elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"22428ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">De Juriste \u00e0 Architecte d'int\u00e9rieur<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-604f434 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"604f434\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ec97ee elementor-widget elementor-widget-text-editor\" data-id=\"8ec97ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Apr\u00e8s 12 ans de carri\u00e8re professionnelle en tant que juriste en droit des affaires, j\u2019ai d\u00e9cid\u00e9 de laisser libre cours \u00e0 ce r\u00eave qui envahissait mon esprit et mon c\u0153ur\u00a0:\u00a0<strong>am\u00e9nager, agencer, cr\u00e9er, optimiser, d\u00e9corer, embellir\u00a0<\/strong>pour donner vie \u00e0 vos envies et \u00e0 vos r\u00eaves\u2026m\u00eame les plus fous !<\/p><p><strong>Dipl\u00f4m\u00e9e de l\u2019\u00e9cole d\u2019architecture d\u2019int\u00e9rieur et de design global &#8211; CREAD<\/strong>, je me suis enfin lanc\u00e9e dans cette belle aventure\u2026 et j\u2019ai d\u00e9cid\u00e9 de faire de cette passion un m\u00e9tier et de mettre toute ma cr\u00e9ativit\u00e9 \u00e0 votre disposition afin de sublimer vos int\u00e9rieurs.<\/p><p>Professionnel ou particulier, c\u2019est avec beaucoup de plaisir que je me d\u00e9placerai jusqu\u2019\u00e0 vous pour discuter <strong>de vos projets de r\u00e9novation partielle ou totale, d\u2019am\u00e9nagement, d\u2019optimisation de volumes, de cr\u00e9ation d\u2019agencements sur mesure, de d\u00e9coration et d\u2019embellissement\u2026<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42242af elementor-widget elementor-widget-text-editor\" data-id=\"42242af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Je serai \u00e0 vos c\u00f4t\u00e9s durant tout le d\u00e9roulement de votre projet, de la conception \u00e0 la coordination et suivi des travaux gr\u00e2ce \u00e0 une \u00e9quipe d\u2019artisans et professionnels parfaitement certifi\u00e9s\u2026Une solution cl\u00e9 en main vous sera propos\u00e9e !<\/strong><\/p><p>Cr\u00e9ative et intuitive, je saurai vous proposer des id\u00e9es harmonieuses et astucieuses qui tiendront compte de vos envies et de vos contraintes qu\u2019elles soient techniques, financi\u00e8res ou esth\u00e9tiques\u2026 la cr\u00e9ativit\u00e9 n\u2019a de limites que celles qu\u2019on lui donne\u2026 ensemble nous d\u00e9passerons ces limites !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13442e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13442e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3714a78\" data-id=\"3714a78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-400b8d4\" data-id=\"400b8d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bea6ae8 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"bea6ae8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sublimesinterieurs.com\/index.php\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PARLONS DE VOS PROJETS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c5d63e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c5d63e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55d1f79\" data-id=\"55d1f79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06d68fb elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"06d68fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">MA MISSION D'ARCHITECTE D\u2019INT\u00c9RIEUR <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc7c886 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"dc7c886\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12ca1ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12ca1ef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eb12882\" data-id=\"eb12882\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1706494 elementor-widget elementor-widget-heading\" data-id=\"1706494\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Phase de conception<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c77dae elementor-widget elementor-widget-text-editor\" data-id=\"4c77dae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Je me charge de toute la phase de conception en vous proposant :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22272f3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"22272f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-pencil-ruler\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">des concepts architecturaux novateurs,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-pencil-ruler\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">des plans d'am\u00e9nagement 2D normalis\u00e9s,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-pencil-ruler\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">de la mod\u00e9lisation 3D de vos espaces incluant visuels photo-r\u00e9alistes.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d25b370 elementor-widget elementor-widget-text-editor\" data-id=\"d25b370\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><strong>Le tout r\u00e9pondant \u00e0 vos attentes, vos contraintes et votre budget.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d3589fb\" data-id=\"d3589fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ece9960 elementor-widget elementor-widget-image\" data-id=\"ece9960\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"525\" height=\"394\" src=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2022\/04\/SDB-Scene-4-1024x768.png\" class=\"attachment-large size-large wp-image-672\" alt=\"\" srcset=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2022\/04\/SDB-Scene-4-1024x768.png 1024w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2022\/04\/SDB-Scene-4-300x225.png 300w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2022\/04\/SDB-Scene-4-768x576.png 768w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2022\/04\/SDB-Scene-4-350x263.png 350w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2022\/04\/SDB-Scene-4.png 1280w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6365486 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6365486\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc6a79f\" data-id=\"fc6a79f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db93462 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"db93462\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"525\" height=\"656\" src=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dinterieur-2-819x1024.jpg\" class=\"attachment-large size-large wp-image-851\" alt=\"Architecte d&apos;int\u00e9rieur\" srcset=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dinterieur-2-819x1024.jpg 819w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dinterieur-2-240x300.jpg 240w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dinterieur-2-768x960.jpg 768w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dinterieur-2-350x438.jpg 350w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dinterieur-2.jpg 1080w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eac9a7a\" data-id=\"eac9a7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dd2b4a elementor-widget elementor-widget-heading\" data-id=\"5dd2b4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Phase de consultation des entreprises et<br> formalit\u00e9s administratives <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76b20e6 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"76b20e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-edit\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Je me charge de toutes les formalit\u00e9s administratives (permis de construire, d\u00e9claration pr\u00e9alable de travaux, modification de fa\u00e7ade, demande d\u2019enseigne, autorisation des travaux, r\u00e8glementation ERP (incendie, PMR...),<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-edit\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Je proc\u00e8de \u00e0 l\u2019\u00e9criture des cahiers des charges techniques en vue de la consultation des entreprises (\u00e9criture de l\u2019ensemble des plans techniques),<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-edit\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Je consulte les entreprises en vue de l\u2019obtention des devis et vous assiste dans la passation des march\u00e9s de travaux,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87b2e7c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"87b2e7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e1481b elementor-widget elementor-widget-heading\" data-id=\"4e1481b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Phase de ma\u00eetrise d\u2019\u0153uvre ou d\u2019assistance \u00e0 ma\u00eetrise d\u2019ouvrage <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-574c013 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"574c013\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hard-hat\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Ma\u00eetrise d\u2019\u0153uvre<\/b> : Je coordonne et j\u2019organise votre chantier de A \u00e0 Z. Je me charge de l\u2019\u00e9criture de planning de chantier et de la coordination de l\u2019ensemble des corps d\u2019\u00e9tat afin de s\u2019assurer de la bonne ex\u00e9cution des travaux dans les d\u00e9lais impartis,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hard-hat\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Assistance \u00e0 ma\u00eetrise d\u2019ouvrage<\/b> :  je vous assisterai pour mener \u00e0 bien votre projet et m\u2019assurerai que celui-ci soit ex\u00e9cut\u00e9 selon les modalit\u00e9s d\u00e9finies lors de son lancement. Je vous ferai b\u00e9n\u00e9ficier de mon expertise technique et de mon exp\u00e9rience, tout au long des travaux.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41b944d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41b944d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-35b9229\" data-id=\"35b9229\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8498734 elementor-widget elementor-widget-heading\" data-id=\"8498734\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Phase de d\u00e9coration<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f25459f elementor-widget elementor-widget-text-editor\" data-id=\"f25459f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Je vous proposerai des shopping lists \u00e0 des tarifs pr\u00e9f\u00e9rentiels n\u00e9goci\u00e9s pour vous aupr\u00e8s des principaux acteurs du design pour\u00a0:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc38673 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"fc38673\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-list-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mobilier,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-list-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Luminaires,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-list-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Accessoires de d\u00e9coration,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-list-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rev\u00eatements muraux,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-list-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rev\u00eatement de sols.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dc4ed31\" data-id=\"dc4ed31\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eeb9e6e elementor-widget elementor-widget-image\" data-id=\"eeb9e6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sublimesinterieurs.com\/wp-content\/uploads\/2021\/10\/2761-web.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c6e078f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c6e078f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-002ffdf\" data-id=\"002ffdf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5e47c9 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"c5e47c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sublimesinterieurs.com\/index.php\/realisations\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DECOUVREZ MES REALISATIONS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24ecd7a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24ecd7a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0577f82\" data-id=\"0577f82\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14772b6 elementor-widget elementor-widget-heading\" data-id=\"14772b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PARTICULIERS-PROFESSIONNELS<br>  Pourquoi faire appel \u00e0 moi pour votre r\u00e9novation int\u00e9rieure?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eecad19 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"eecad19\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b56a9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b56a9a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-582a826\" data-id=\"582a826\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-926a8f8 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"926a8f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur.png\" class=\"elementor-animation-grow attachment-full size-full wp-image-884\" alt=\"Architecte d&apos;Int\u00e9rieur\" srcset=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur.png 500w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-300x300.png 300w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-150x150.png 150w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-100x100.png 100w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-350x350.png 350w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Un seul interlocuteur<\/h3><p class=\"elementor-image-box-description\">Je serai votre interlocuteur privil\u00e9gi\u00e9  pour l\u2019ensemble de votre projet de r\u00e9novation: de la conception au suivi de chantier<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f6d9b68\" data-id=\"f6d9b68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-334f6e6 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"334f6e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-1.png\" class=\"elementor-animation-grow attachment-full size-full wp-image-885\" alt=\"Architecte d&apos;Int\u00e9rieur\" srcset=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-1.png 500w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-1-300x300.png 300w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-1-150x150.png 150w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-1-100x100.png 100w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-1-350x350.png 350w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Des artisans s\u00e9lectionn\u00e9s<\/h3><p class=\"elementor-image-box-description\">Vous b\u00e9n\u00e9ficiez d\u2019une mise en relation avec des artisans s\u00e9lectionn\u00e9s pour leur s\u00e9rieux et leur professionnalisme avec lesquels j\u2019ai l\u2019habitude de travailler et en lesquels j\u2019ai totale confiance<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-70de180\" data-id=\"70de180\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c87e1ef elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"c87e1ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-2.png\" class=\"elementor-animation-grow attachment-full size-full wp-image-886\" alt=\"Architecte d&apos;Int\u00e9rieur\" srcset=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-2.png 500w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-2-300x300.png 300w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-2-150x150.png 150w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-2-100x100.png 100w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-2-350x350.png 350w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Mon expertise \u00e0 votre service<\/h3><p class=\"elementor-image-box-description\">Vous b\u00e9n\u00e9ficiez de mon expertise pass\u00e9e de juriste en droit des affaires qui me donne un avantage consid\u00e9rable dans la gestion et la bonne ex\u00e9cution des projets dans les d\u00e9lais impartis et qui m\u2019offre une certaine aisance dans la gestion des formalit\u00e9s administratives et contractuelles<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4dadb8e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4dadb8e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-875fcb8\" data-id=\"875fcb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe05604 elementor-widget elementor-widget-spacer\" data-id=\"fe05604\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06f6623 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06f6623\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34c0a66\" data-id=\"34c0a66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e7f1b2 elementor-widget elementor-widget-heading\" data-id=\"8e7f1b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ILS EN PARLENT MIEUX QUE MOI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0103e02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0103e02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-debbe5a\" data-id=\"debbe5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4601de5 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"4601de5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdab89b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdab89b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a4a0e8\" data-id=\"0a4a0e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26f3f5f elementor-widget elementor-widget-shortcode\" data-id=\"26f3f5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-disable-font ti-show-rating-text ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-plugin-version=\"13.3.2\" data-layout-id=\"4\" data-layout-category=\"slider\" data-set-id=\"soft\" data-pid=\"\" data-language=\"fr\" data-close-locale=\"Fermer\" data-review-target-width=\"300\" data-css-version=\"2\" data-reply-by-locale=\"R\u00e9ponse du propri\u00e9taire\" data-only-rating-locale=\"Cet utilisateur a uniquement laiss\u00e9 une \u00e9valuation.\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-3\"> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Avis suivante\" role=\"button\" tabindex=\"0\"><\/div> <div class=\"ti-prev\" aria-label=\"Avis pr\u00e9c\u00e9dent\" role=\"button\" tabindex=\"0\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIUe6TqdBE0uBFvahLlWGPadOntVJV45FcpitGsC7ROD0XXFw=w40-h40-c-rp-mo-br100\" alt=\"Dani\u00e8le Jacquard profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Dani\u00e8le Jacquard <\/div> <div class=\"ti-date\">26\/11\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Professionnelle, \u00e0 l'\u00e9coute, projet d'am\u00e9nagement pr\u00e9sent\u00e9 innovant, respect du contrat et des d\u00e9lais (suivi de chantier assur\u00e9), mise en relation avec v\u00e9ritables artisans, r\u00e9sultat \"int\u00e9rieur sublim\u00e9\"<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjX9DMMPlt7p2hIROF2Vh9Fs449q2aNruw7NMw7VYZW0OG1lupQ=w40-h40-c-rp-mo-br100\" alt=\"Marie Manant profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Marie Manant <\/div> <div class=\"ti-date\">25\/11\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->C\u00e9line sait \u00eatre \u00e0 votre \u00e9coute, transformer vos id\u00e9es, proposer des solutions originales esth\u00e9tiques et fonctionnelles, et ainsi \u00ab\u00a0sublimer\u00a0\u00bb votre int\u00e9rieur tout en respectant votre adn et votre budget, en \u00e9quipe avec des artisans de qualit\u00e9. Je la recommande sans r\u00e9serve !<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKFwKBX5IIPkquUBDbmRUClty_qCDX_STT6Wspo0Tk0ChXoaA=w40-h40-c-rp-mo-br100\" alt=\"Olivier Foures profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Olivier Foures <\/div> <div class=\"ti-date\">25\/09\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Nous avons fait appel \u00e0 C\u00e9line pour la r\u00e9novation de notre salon dans une maison ancienne, ce qui incluait \u00e9galement la partie mezzanine de cette pi\u00e8ce. Nous voulions retrouver une utilit\u00e9 \u00e0 cette pi\u00e8ce et cr\u00e9er une atmosph\u00e8re chaleureuse propice aux r\u00e9unions en famille et entre amis. Le rendu est magnifique et nous sommes ravis. Le dialogue avec C\u00e9line a \u00e9t\u00e9 constant et nous avons \u00e9t\u00e9 s\u00e9duits par les nombreuses id\u00e9es d\u00e9co qu\u2019elle a apport\u00e9es, auxquelles nous n\u2019aurions jamais pens\u00e9. Longtemps la pi\u00e8ce d\u00e9laiss\u00e9e de la maison, elle en est devenue centrale. Et C\u00e9line nous a d\u00e9charg\u00e9 des parties administratives, commandes, suivi avec les artisans, avec r\u00e9activit\u00e9 et efficacit\u00e9. L\u2019ensemble du projet s\u2019est d\u00e9roul\u00e9 magnifiquement et nous avons r\u00e9uni l\u2019ensemble des acteurs \u00e0 l\u2019issue pour les remercier par en quelque sorte une nouvelle pendaison de cr\u00e9maill\u00e8re.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUcC_xUgQ9U1HCX2n4m3po97LHp6ru2uc5oO_hzEBkQ27CyzUTQ=w40-h40-c-rp-mo-ba2-br100\" alt=\"magali willemin profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> magali willemin <\/div> <div class=\"ti-date\">22\/09\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->J'ai fait appel \u00e0 C\u00e9line pour refaire enti\u00e8rement notre salle de bain.\nForce de proposition, \u00e0 l'\u00e9coute et surtout elle nous a dessin\u00e9 un meuble sur mesure car notre salle de bain est un peu atypique!\nElle s'adapte \u00e0 toutes les demandes et tous les budgets.\nDes plans techniques tr\u00e8s pr\u00e9cis pour les artisans, des plans 3D pour nous projeter.\nNous sommes ravis du r\u00e9sultat et recommandons fortement C\u00e9line pour son professionnalisme, sa r\u00e9activit\u00e9 et son imagination qui feront de vos projets des projets uniques!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKSVSOcN6LE7H2EZXhazGq2AWORkt7s1jXC1dBgNog6Ov9c-Q=w40-h40-c-rp-mo-br100\" alt=\"Erika Ferlay profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Erika Ferlay <\/div> <div class=\"ti-date\">29\/07\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Nous avons fait appel \u00e0 C\u00e9line dans le cadre d'une r\u00e9novation et d'am\u00e9nagement de bureaux. Son accompagnement a \u00e9t\u00e9 parfait d'un bout \u00e0 l'autre du projet: elle a \u00e9t\u00e9 \u00e0 l'\u00e9coute pour comprendre nos besoins et nos go\u00fbts, a assur\u00e9 la coordination et le suivi du chantier d'une main de ma\u00eetre, a su nous \u00e9clairer sur certaines contraintes techniques, et s'est entour\u00e9e d'artisans s\u00e9rieux. Tr\u00e8s r\u00e9active, elle a trouv\u00e9 des solutions \u00e0 chaque difficult\u00e9 qui se pr\u00e9sentait (et il y a en a eu quelques unes!). Je n'h\u00e9siterai pas \u00e0 refaire appel \u00e0 C\u00e9line si j'ai un autre projet, perso ou pro.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWqeHFtq92F1QDVrByhgajNnHeYcvk9T6QglLMaYqbHoxbylWNc=w40-h40-c-rp-mo-br100\" alt=\"Liz Alderete profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Liz Alderete <\/div> <div class=\"ti-date\">29\/07\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Nous avons eu la chance de faire appel \u00e0 C\u00e9line  pour la r\u00e9novation et l\u2019agrandissement de notre maison familiale, et nous en sommes pleinement satisfaits ! Tr\u00e8s \u00e0 l\u2019\u00e9coute, professionnelle et force de proposition, elle a su parfaitement comprendre nos besoins et respecter notre cahier des charges. Chaque d\u00e9tail a \u00e9t\u00e9 pens\u00e9 avec soin, et le r\u00e9sultat est \u00e0 la hauteur (voire au-del\u00e0) de nos attentes. Une vraie partenaire de confiance pour mener \u00e0 bien un projet aussi important. Nous la recommandons sans h\u00e9siter !<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJGuLUhq1tFr6iz60Aa1nYLSHawG4unwin-fiL10XPRtNdOzw=w40-h40-c-rp-mo-br100\" alt=\"D\u00e9borah BENAROUS profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> D\u00e9borah BENAROUS <\/div> <div class=\"ti-date\">25\/07\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Nous avons fait appel \u00e0 C\u00e9line pour la r\u00e9novation totale de nos locaux professionnels. Elle a su tout g\u00e9rer et coordonner avec professionnalisme, disponibilit\u00e9 et bienveillance. C\u2019est un r\u00e9el soulagement d\u2019avoir faire appel \u00e0 C\u00e9line qui est totalement investie dans les projets qu\u2019on peut lui confier. Merci!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKzcyVJr4XQS5-nzUZVUASoBwJxkqAE_OP8_LMFHRT26CaTaA=w40-h40-c-rp-mo-br100\" alt=\"Karine Gouteyron profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Karine Gouteyron <\/div> <div class=\"ti-date\">24\/07\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->J'ai fait appel \u00e0 C\u00e9line pour la r\u00e9novation compl\u00e8te d'un local professionnel. Je suis ravie de sa prestation. Elle est disponible, efficace et trouve toujours des solutions.\nL'accompagnement cl\u00e9 en main est vraiment appr\u00e9ciable.\nJe vous la recommande \u00e0 1000%.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjX01TENccOxuMEPFBciXTv86lSZ3d427zCwTiov1hISSO-ba2lb=w40-h40-c-rp-mo-ba2-br100\" alt=\"Charlie Menut profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Charlie Menut <\/div> <div class=\"ti-date\">24\/07\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Nous avons fait appel \u00e0 C\u00e9line pour la r\u00e9novation de nos locaux professionnels et nous sommes ravis. Elles s'est occup\u00e9 de tout : des plans 3D aux plans techniques, des d\u00e9marches aupr\u00e8s des services d'urbanisme, de la ma\u00eetrise d'\u0153uvre et j'en oublie certainement... bref un vrai soulagement \ud83d\ude00 nous la remercions chaleureusement d'avoir su nous proposer un projet correspondant \u00e0 nos demandes, pas facile quand il faut concilier les go\u00fbts de 4 personnalit\u00e9s diff\u00e9rentes ! Nous la recommandons tr\u00e8s fortement . Merci C\u00e9line<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJ0-1TegYJUTZ6Orvl-m1mgbowzFlarpXQ5pVfZ2BzZ1uTkQg=w40-h40-c-rp-mo-br100\" alt=\"Olivier Desormiere profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Olivier Desormiere <\/div> <div class=\"ti-date\">10\/07\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Nous avons fait appel \u00e0 C\u00e9line pour la r\u00e9novation d\u2019une maison des ann\u00e9es 30. Elle a su nous conseiller sur la redistribution des pi\u00e8ces et sur la d\u00e9coration int\u00e9rieure en prenant en compte nos envies et nos contraintes. Elle a surtout coordonn\u00e9 les travaux, ceci nous paraissait la partie la plus compliqu\u00e9e . Tout s\u2019est pass\u00e9 super bien. C\u00e9line a une bonne humeur et un enthousiasme communicatifs ! Nous feront appel \u00e0 son entreprise lors de notre prochaine r\u00e9novation.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div> <\/div> <div class=\"ti-footer\"> <div class=\"ti-rating-text\"> <span class=\"nowrap\">\u00c9valuation <strong>Google<\/strong> : <\/span><span class=\"nowrap\"><strong>5.0<\/strong> sur 5, <\/span><span class=\"nowrap\">Bas\u00e9e sur <strong>23 avis<\/strong><\/span> <\/div> <\/div>   <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/trustindex-google-widget.css?1787087780\"><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-953ffc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"953ffc0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25d4cb8\" data-id=\"25d4cb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2ae089 elementor-widget elementor-widget-spacer\" data-id=\"b2ae089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0572602 elementor-widget elementor-widget-heading\" data-id=\"0572602\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CADEAU D\u00c9CORATION INT\u00c9RIEURE!! <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4c3086 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4c3086\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd7619c\" data-id=\"dd7619c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55dc9c7 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"55dc9c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5d0330 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5d0330\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-61a5544\" data-id=\"61a5544\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ec126a elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1ec126a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"525\" src=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/03\/Cadeau-Decoration-Interieure-1024x1024.jpg\" class=\"attachment-large size-large wp-image-1793\" alt=\"Cadeau D\u00e9coration Int\u00e9rieure\" srcset=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/03\/Cadeau-Decoration-Interieure-1024x1024.jpg 1024w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/03\/Cadeau-Decoration-Interieure-300x300.jpg 300w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/03\/Cadeau-Decoration-Interieure-150x150.jpg 150w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/03\/Cadeau-Decoration-Interieure-768x768.jpg 768w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/03\/Cadeau-Decoration-Interieure-1536x1536.jpg 1536w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/03\/Cadeau-Decoration-Interieure-100x100.jpg 100w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/03\/Cadeau-Decoration-Interieure-350x350.jpg 350w, https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/03\/Cadeau-Decoration-Interieure.jpg 2048w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2512e3d\" data-id=\"2512e3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8fce4a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e8fce4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_mobile&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Offrez un bon cadeau \u00e0 vos proches<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f5c074 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"9f5c074\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc6c082 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"fc6c082\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_mobile&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous connaissez quelqu\u2019un qui aurait besoin de conseils pour une d\u00e9coration ou r\u00e9novation int\u00e9rieure?<\/p><p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><strong>OFFREZ-LUI UN BON CADEAU DECO!<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49fe471 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"49fe471\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_mobile&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>1h ou 1h30 de conseils d\u00e9coration et r\u00e9novation<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Lyon et 35km autour<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-money-bill-wave\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>150\u20ac TTC pour 1h et 180\u20ac TTC pour 1h30<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3048ca1 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"3048ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sublimesinterieurs.com\/index.php\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTACTEZ-MOI POUR EN SAVOIR PLUS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7517d26 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7517d26\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e7ac63a\" data-id=\"e7ac63a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2ab47da\" data-id=\"2ab47da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e6dbc7 elementor-widget elementor-widget-spacer\" data-id=\"7e6dbc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdaa397 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"bdaa397\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Pour rendre vos int\u00e9rieurs<BR>SUBLIMES<br><br><br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3b59b7 elementor-widget elementor-widget-spacer\" data-id=\"e3b59b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e163c7 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"3e163c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sublimesinterieurs.com\/index.php\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTACTEZ-MOI<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-56cb975\" data-id=\"56cb975\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9er, ce n\u2019est pas reproduire ce qui existe d\u00e9j\u00e0, ce n\u2019est pas non plus faire une belle image mais faire \u00e0 son image&#8230;by C\u00e9line De Juriste \u00e0 Architecte d&rsquo;int\u00e9rieur Apr\u00e8s 12 ans de carri\u00e8re professionnelle en tant que juriste en droit des affaires, j\u2019ai d\u00e9cid\u00e9 de laisser libre cours \u00e0 ce r\u00eave qui envahissait mon &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.sublimesinterieurs.com\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Accueil&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-6","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accueil - Sublimes Int\u00e9rieurs By C\u00e9line<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sublimesinterieurs.com\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accueil - Sublimes Int\u00e9rieurs By C\u00e9line\" \/>\n<meta property=\"og:description\" content=\"Cr\u00e9er, ce n\u2019est pas reproduire ce qui existe d\u00e9j\u00e0, ce n\u2019est pas non plus faire une belle image mais faire \u00e0 son image&#8230;by C\u00e9line De Juriste \u00e0 Architecte d&rsquo;int\u00e9rieur Apr\u00e8s 12 ans de carri\u00e8re professionnelle en tant que juriste en droit des affaires, j\u2019ai d\u00e9cid\u00e9 de laisser libre cours \u00e0 ce r\u00eave qui envahissait mon &hellip; Continuer la lecture de &laquo;&nbsp;Accueil&nbsp;&raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sublimesinterieurs.com\/\" \/>\n<meta property=\"og:site_name\" content=\"Sublimes Int\u00e9rieurs By C\u00e9line\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-13T14:02:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-768x1151.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sublimesinterieurs.com\/\",\"url\":\"https:\/\/www.sublimesinterieurs.com\/\",\"name\":\"Accueil - Sublimes Int\u00e9rieurs By C\u00e9line\",\"isPartOf\":{\"@id\":\"https:\/\/www.sublimesinterieurs.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sublimesinterieurs.com\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sublimesinterieurs.com\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-768x1151.jpg\",\"datePublished\":\"2019-03-17T05:35:00+00:00\",\"dateModified\":\"2024-05-13T14:02:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sublimesinterieurs.com\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sublimesinterieurs.com\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sublimesinterieurs.com\/#primaryimage\",\"url\":\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-scaled.jpg\",\"contentUrl\":\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-scaled.jpg\",\"width\":1709,\"height\":2560,\"caption\":\"Architecte d'int\u00e9rieur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sublimesinterieurs.com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.sublimesinterieurs.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sublimesinterieurs.com\/#website\",\"url\":\"https:\/\/www.sublimesinterieurs.com\/\",\"name\":\"Sublimes Int\u00e9rieurs By C\u00e9line\",\"description\":\"Agence d&#039;architecture et de d\u00e9coration d&#039;int\u00e9rieur\",\"publisher\":{\"@id\":\"https:\/\/www.sublimesinterieurs.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sublimesinterieurs.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sublimesinterieurs.com\/#organization\",\"name\":\"Sublimes Int\u00e9rieurs By C\u00e9line\",\"url\":\"https:\/\/www.sublimesinterieurs.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sublimesinterieurs.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2019\/03\/cropped-cropped-favicon-1.png\",\"contentUrl\":\"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2019\/03\/cropped-cropped-favicon-1.png\",\"width\":250,\"height\":250,\"caption\":\"Sublimes Int\u00e9rieurs By C\u00e9line\"},\"image\":{\"@id\":\"https:\/\/www.sublimesinterieurs.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil - Sublimes Int\u00e9rieurs By C\u00e9line","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sublimesinterieurs.com\/","og_locale":"fr_FR","og_type":"article","og_title":"Accueil - Sublimes Int\u00e9rieurs By C\u00e9line","og_description":"Cr\u00e9er, ce n\u2019est pas reproduire ce qui existe d\u00e9j\u00e0, ce n\u2019est pas non plus faire une belle image mais faire \u00e0 son image&#8230;by C\u00e9line De Juriste \u00e0 Architecte d&rsquo;int\u00e9rieur Apr\u00e8s 12 ans de carri\u00e8re professionnelle en tant que juriste en droit des affaires, j\u2019ai d\u00e9cid\u00e9 de laisser libre cours \u00e0 ce r\u00eave qui envahissait mon &hellip; Continuer la lecture de &laquo;&nbsp;Accueil&nbsp;&raquo;","og_url":"https:\/\/www.sublimesinterieurs.com\/","og_site_name":"Sublimes Int\u00e9rieurs By C\u00e9line","article_modified_time":"2024-05-13T14:02:32+00:00","og_image":[{"url":"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-768x1151.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sublimesinterieurs.com\/","url":"https:\/\/www.sublimesinterieurs.com\/","name":"Accueil - Sublimes Int\u00e9rieurs By C\u00e9line","isPartOf":{"@id":"https:\/\/www.sublimesinterieurs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sublimesinterieurs.com\/#primaryimage"},"image":{"@id":"https:\/\/www.sublimesinterieurs.com\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-768x1151.jpg","datePublished":"2019-03-17T05:35:00+00:00","dateModified":"2024-05-13T14:02:32+00:00","breadcrumb":{"@id":"https:\/\/www.sublimesinterieurs.com\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sublimesinterieurs.com\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sublimesinterieurs.com\/#primaryimage","url":"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-scaled.jpg","contentUrl":"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2024\/01\/Architecte-dInterieur-scaled.jpg","width":1709,"height":2560,"caption":"Architecte d'int\u00e9rieur"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sublimesinterieurs.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sublimesinterieurs.com\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/www.sublimesinterieurs.com\/#website","url":"https:\/\/www.sublimesinterieurs.com\/","name":"Sublimes Int\u00e9rieurs By C\u00e9line","description":"Agence d&#039;architecture et de d\u00e9coration d&#039;int\u00e9rieur","publisher":{"@id":"https:\/\/www.sublimesinterieurs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sublimesinterieurs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.sublimesinterieurs.com\/#organization","name":"Sublimes Int\u00e9rieurs By C\u00e9line","url":"https:\/\/www.sublimesinterieurs.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sublimesinterieurs.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2019\/03\/cropped-cropped-favicon-1.png","contentUrl":"https:\/\/www.sublimesinterieurs.com\/wp-content\/uploads\/2019\/03\/cropped-cropped-favicon-1.png","width":250,"height":250,"caption":"Sublimes Int\u00e9rieurs By C\u00e9line"},"image":{"@id":"https:\/\/www.sublimesinterieurs.com\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"twentyseventeen-featured-image":false,"twentyseventeen-thumbnail-avatar":false,"blog-list-post-size":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.sublimesinterieurs.com\/index.php\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Cr\u00e9er, ce n\u2019est pas reproduire ce qui existe d\u00e9j\u00e0, ce n\u2019est pas non plus faire une belle image mais faire \u00e0 son image&#8230;by C\u00e9line De Juriste \u00e0 Architecte d&rsquo;int\u00e9rieur Apr\u00e8s 12 ans de carri\u00e8re professionnelle en tant que juriste en droit des affaires, j\u2019ai d\u00e9cid\u00e9 de laisser libre cours \u00e0 ce r\u00eave qui envahissait mon\u2026","_links":{"self":[{"href":"https:\/\/www.sublimesinterieurs.com\/index.php\/wp-json\/wp\/v2\/pages\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sublimesinterieurs.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sublimesinterieurs.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sublimesinterieurs.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sublimesinterieurs.com\/index.php\/wp-json\/wp\/v2\/comments?post=6"}],"version-history":[{"count":202,"href":"https:\/\/www.sublimesinterieurs.com\/index.php\/wp-json\/wp\/v2\/pages\/6\/revisions"}],"predecessor-version":[{"id":1926,"href":"https:\/\/www.sublimesinterieurs.com\/index.php\/wp-json\/wp\/v2\/pages\/6\/revisions\/1926"}],"wp:attachment":[{"href":"https:\/\/www.sublimesinterieurs.com\/index.php\/wp-json\/wp\/v2\/media?parent=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}